{"id":2752,"date":"2023-01-24T17:53:51","date_gmt":"2023-01-24T17:53:51","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/peugeot-michelin-esso\/"},"modified":"2026-05-13T15:38:40","modified_gmt":"2026-05-13T13:38:40","slug":"peugeot-michelin-esso","status":"publish","type":"product","link":"https:\/\/www.ton.connectingminds.net\/it\/retro-wielershirt\/peugeot-michelin-esso\/","title":{"rendered":"PEUGEOT (c)-MICHELIN-ESSO \u2013 1981 \u2013 MAGLIA DA CICLISMO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2751,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-2752","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PEUGEOT (c)-MICHELIN-ESSO - 1981 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PEUGEOT (c)-MICHELIN-ESSO - 1981 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:38:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43524.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/\",\"name\":\"PEUGEOT (c)-MICHELIN-ESSO - 1981 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43524.jpg\",\"datePublished\":\"2023-01-24T17:53:51+00:00\",\"dateModified\":\"2026-05-13T13:38:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43524.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43524.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cyclingoriginals.com\\\/pt\\\/retro-wielershirt\\\/peugeot-michelin-esso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PEUGEOT (c)-MICHELIN-ESSO &#8211; 1981 &#8211; WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PEUGEOT (c)-MICHELIN-ESSO - 1981 - MAGLIA CICLISMO - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/","og_locale":"it_IT","og_type":"article","og_title":"PEUGEOT (c)-MICHELIN-ESSO - 1981 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:38:40+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.cyclingoriginals.com\/wp-content\/uploads\/2023\/01\/SSA43524.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/","url":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/","name":"PEUGEOT (c)-MICHELIN-ESSO - 1981 - MAGLIA CICLISMO - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/#primaryimage"},"image":{"@id":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/SSA43524.jpg","datePublished":"2023-01-24T17:53:51+00:00","dateModified":"2026-05-13T13:38:40+00:00","breadcrumb":{"@id":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/#primaryimage","url":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/SSA43524.jpg","contentUrl":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/SSA43524.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cyclingoriginals.com\/pt\/retro-wielershirt\/peugeot-michelin-esso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"PEUGEOT (c)-MICHELIN-ESSO &#8211; 1981 &#8211; WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/product\/2752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/media\/2751"}],"wp:attachment":[{"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/media?parent=2752"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/product_brand?post=2752"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/product_cat?post=2752"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ton.connectingminds.net\/it\/wp-json\/wp\/v2\/product_tag?post=2752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}